{"id":10,"date":"2023-02-21T14:52:26","date_gmt":"2023-02-21T14:52:26","guid":{"rendered":"https:\/\/marcomannucci.it\/?page_id=10"},"modified":"2025-09-18T13:42:10","modified_gmt":"2025-09-18T13:42:10","slug":"home","status":"publish","type":"page","link":"https:\/\/marcomannucci.it\/","title":{"rendered":"Home"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19 size-full\" src=\"https:\/\/marcomannucci.it\/wp-content\/uploads\/2023\/02\/home-studio-mannucci_slide01G-1024x682-1.jpg\" alt=\"\" width=\"1024\" height=\"682\" srcset=\"https:\/\/marcomannucci.it\/wp-content\/uploads\/2023\/02\/home-studio-mannucci_slide01G-1024x682-1.jpg 1024w, https:\/\/marcomannucci.it\/wp-content\/uploads\/2023\/02\/home-studio-mannucci_slide01G-1024x682-1-300x200.jpg 300w, https:\/\/marcomannucci.it\/wp-content\/uploads\/2023\/02\/home-studio-mannucci_slide01G-1024x682-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Lo <strong>Studio MANNUCCI &#8211; <\/strong><strong><em>Tax &amp; Legal<\/em><\/strong><em> \u2013 <\/em>dal 2005 offre Consulenza e Assistenza Tributaria, Societaria, Aziendale, Commerciale, Contabile e Legale a livello nazionale ed internazionale.<\/p>\n<p>I professionisti che vi operano, vantano esperienze di primo piano nell\u2019assistenza di importanti gruppi nazionali e sono in grado di valutare e rispondere al meglio alle esigenze di aziende di ogni livello, nazionali e straniere, e intendono anche avvalersi delle opportunit\u00e0 offerte dalle molteplici risorse economiche dei vari Stati attraverso l\u2019attivit\u00e0 di pianificazione fiscale internazionale.<\/p>\n<p>Professionalit\u00e0, concretezza e determinazione contraddistinguono le figure professionali che operano all\u2019interno dello <strong>Studio <\/strong>garantendo trasparenza e affidabilit\u00e0 nei rapporti con la clientela.<\/p>\n<p>Lo <strong>Studio<\/strong>, con sede a Milano, avvalendosi di un network di corrispondenti e di partnership professionali in Italia e all\u2019estero, dispone di una struttura flessibile capace di fornire al Cliente un servizio altamente professionale con la massima disponibilit\u00e0 e celerit\u00e0.<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-51\" src=\"https:\/\/marcomannucci.it\/wp-content\/uploads\/2025\/09\/Logo-IICUAE.webp\" alt=\"\" width=\"300\" height=\"170\" \/><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo Studio MANNUCCI &#8211; Tax &amp; Legal \u2013 dal 2005 offre Consulenza e Assistenza Tributaria, Societaria, Aziendale, Commerciale, Contabile e Legale a livello nazionale ed internazionale. I professionisti che vi operano, vantano esperienze di primo piano nell\u2019assistenza di importanti gruppi nazionali e sono in grado di valutare e rispondere al meglio alle esigenze di aziende&hellip; <span class=\"kuorinka-read-more\"><a href=\"https:\/\/marcomannucci.it\/\" class=\"more-link\">Continua a leggere <span class=\"screen-reader-text\">Home<\/span><\/a><\/span><\/p>\n","protected":false},"author":22,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10","page","type-page","status-publish","entry"],"_links":{"self":[{"href":"https:\/\/marcomannucci.it\/index.php\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcomannucci.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/marcomannucci.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/marcomannucci.it\/index.php\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/marcomannucci.it\/index.php\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":3,"href":"https:\/\/marcomannucci.it\/index.php\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":52,"href":"https:\/\/marcomannucci.it\/index.php\/wp-json\/wp\/v2\/pages\/10\/revisions\/52"}],"wp:attachment":[{"href":"https:\/\/marcomannucci.it\/index.php\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}